{"id":16397,"date":"2024-07-15T10:10:35","date_gmt":"2024-07-15T08:10:35","guid":{"rendered":"https:\/\/www.seval.ch\/newsletter\/nl-no-38-february-2024-copy\/"},"modified":"2024-07-17T09:13:38","modified_gmt":"2024-07-17T07:13:38","slug":"nl-no-39-july-2024","status":"publish","type":"newsletter","link":"https:\/\/www.seval.ch\/it\/newsletter\/nl-no-39-july-2024\/","title":{"rendered":"Newsletter no. 39, July 2024"},"content":{"rendered":"<p><strong>Editorial<\/strong><\/p>\n<div>\n<p>Die Arbeitsgruppen sind der Antrieb der SEVAL. Ihre zahlreichen Aktivit\u00e4ten zeugen von ihrer Dynamik. In diesem Newsletter finden Sie inspirierende Berichte \u00fcber die Ereignisse der letzten Monate. Ausserdem finden Sie ein Portr\u00e4t des ersten Gewinners des Stipendiums zur F\u00f6rderung des Nachwuchses in der Evaluation.<br \/>\nDer Jahreskongress ist die wichtigste Veranstaltung der SEVAL und die Gelegenheit, uns wiederzusehen. Das Organisationskomitee hat ein spannendes Programm voller Entdeckungen zusammengestellt. Im Mittelpunkt steht die Kommunikation, ein Thema, das uns alle besch\u00e4ftigt, um unser Vorgehen und unsere Ergebnisse besser zug\u00e4nglich zu machen. Melden Sie sich an, kommen Sie zahlreich und verbreiten Sie die Informationen in Ihrem Umfeld!<\/p>\n<p>Laurent Cr\u00e9mieux<br \/>\nVorstandsmitglied der SEVAL<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h2>Themen<\/h2>\n<ul>\n<li><a href=\"#absatz_1\">Aktivit\u00e4ten und Mitteilungen der SEVAL<\/a><\/li>\n<li><a href=\"#absatz_2\">Internationales<\/a><\/li>\n<li><a href=\"#absatz_3\">Aus- und Weiterbildung<\/a><\/li>\n<li><a href=\"#absatz_4\">Informationen aus den Arbeitsgruppen<\/a><\/li>\n<li><a href=\"#absatz_5\">Agenda<\/a><\/li>\n<li><a href=\"#absatz_6\">Publikationen<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h3><a id=\"absatz_1\"><\/a>Aktivit\u00e4ten und Mitteilungen der SEVAL\u00a0<em><br \/>\n<\/em><\/h3>\n<hr \/>\n<h4>Kongress 2024: Anmeldung er\u00f6ffnet<\/h4>\n<p>Der diesj\u00e4hrige Jahreskongress der SEVAL, der gemeinsam mit dem GREVAL organisiert wird, findet am 29. und 30. August statt und tr\u00e4gt den Titel <strong>\u00abImage und Wahrnehmung der Evaluation. Sind wir zu technokratisch?\u00bb<\/strong>. Schauen Sie sich das <a href=\"https:\/\/www.seval.ch\/news-veranstaltungen\/veranstaltungen\/seval-kongress-2024\/\" target=\"_blank\" rel=\"noopener\"><strong>Programm<\/strong><\/a> an!<\/p>\n<p>Die Evaluation wird nicht immer als ein Instrument zur Verbesserung des \u00f6ffentlichen Handelns wahrgenommen. Wer hat nicht schon einmal geh\u00f6rt, Evaluationen w\u00fcrden viel kosten und nichts bringen? K\u00f6nnen solche Klischees \u00fcberwunden werden? Sie begr\u00fcnden sich anscheinend unter anderem mit einer teilweise zu technokratischen Kommunikation von Evaluierenden mit den verschiedenen Interessengruppen wie z.B. mit Zielgruppen, potenziellen Nutzern und der breiten \u00d6ffentlichkeit<\/p>\n<p>Anhand von Pr\u00e4sentationen von Fachpersonen sowohl f\u00fcr Evaluation als auch f\u00fcr Kommunikation er\u00f6rtern wir Strategien, um das Verst\u00e4ndnis f\u00fcr Evaluation bei Personen ohne Fachkenntnisse in diesem Bereich zu f\u00f6rdern. Das Programm l\u00e4sst auch Raum f\u00fcr Diskussionen und f\u00fcr Erfahrungsaustausch zwischen praktizierenden Evaluatorinnen und Evaluatoren und allen anderen Interessierten.<\/p>\n<p>Der Nachmittag des 29. August beinhaltet neben den traditionellen Methodenateliers auch einen Side-Event f\u00fcr aufstrebende Evaluatorinnen und Evaluatoren sowie Tandem-Diskussionen zwischen jeweils einzelnen aufstrebenden und erfahrenen Evaluierenden. Das diesj\u00e4hrige Angebot an Ateliers ist umfangreich und vielf\u00e4ltig. Alle k\u00f6nnen an vier Ateliers (auf Deutsch, Franz\u00f6sisch oder zweisprachig) teilnehmen.<\/p>\n<hr \/>\n<h4>SEVAL-Stipendium 2024<\/h4>\n<h3><strong>Das SEVAL-Stipendium zur Nachwuchsf\u00f6rderung geht in die zweite Runde<\/strong><\/h3>\n<p>Nachdem das SEVAL-Stipendium letztes Jahr zum ersten Mal vergeben wurde, k\u00f6nnen sich auch dieses Jahr interessierte junge, angehende Fachleute auf das CAS- und\/oder Praktikums-Stipendium bewerben.<\/p>\n<p>Kennen Sie junge Nachwuchstalente? Dann z\u00f6gern Sie nicht, sie zur Bewerbung auf das Stipendium einzuladen!<\/p>\n<p>Mehr Informationen <a href=\"https:\/\/www.seval.ch\/stipendium-prix-seval\/seval-stipendium\/\" target=\"_blank\" rel=\"noopener\">hier<\/a><\/p>\n<p><strong>***<\/strong><\/p>\n<h4>SEVAL-Stipendium 2023<\/h4>\n<h3><b>Gewinner des Nachwuchsstipendiums 2023<\/b><\/h3>\n<p>Das Nachwuchsstipendium 2023 wurde an Rasman\u00e9 Sina verliehen, um ein CAS am IDHEAP zu absolvieren. Die Jury hatte rund zehn Bewerbungen erhalten.<\/p>\n<h6>&#8211; Rasman\u00e9 Sina, was ist Ihr Werdegang?<\/h6>\n<p><em>Als Lehrbeauftragter f\u00fcr Wirtschaftswissenschaften an der Universit\u00e4t Genf besch\u00e4ftige ich mich intensiv mit Fragen der Analyse von wirtschaftlichen Entwicklungspolitiken, dem Management von Projekten und Programmen und der Evaluation \u00f6ffentlicher Politiken. Dabei gehe ich von meiner universit\u00e4ren Grundausbildung aus, die in der makro\u00f6konomischen Analyse der Entwicklung, der Wirtschafts- und Sozialpolitik und vor allem in den gemischten (quantitativen und qualitativen) Methoden, die in den Sozialwissenschaften angewandt werden, besteht.<\/em><\/p>\n<h6>&#8211; Warum haben Sie sich f\u00fcr das Stipendium beworben? Worin besteht der Mehrwert f\u00fcr Sie?<\/h6>\n<p><em>Meine Bewerbung f\u00fcr das Stipendium der Schweizerischen Evaluationsgesellschaft (SEVAL) ist aus zwei Gr\u00fcnden motiviert. Erstens, um Zugang zu einer sehr fortgeschrittenen und hochspezialisierten Ausbildung in Politikbewertung am renommierten Institut des hautes \u00e9tudes en administration publique (IDHEAP) zu erhalten, und zweitens, um der SEVAL beitreten zu k\u00f6nnen, um meinen Beitrag an technischen Kompetenzen und zur Diversifizierung der Methoden der Politikbewertung sowohl in der Schweiz als auch auf internationaler Ebene leisten zu k\u00f6nnen.<\/em><\/p>\n<h6>&#8211; Welche Erfahrungen haben Sie mit dem CAS am IDHEAP gemacht?<\/h6>\n<p><em>Die CAS-Ausbildung ist f\u00fcr mich eine reiche Erfahrung mit einer St\u00e4rkung meiner Kompetenzen in der Methodik und den Techniken der Evaluation \u00f6ffentlicher Politiken und der Verwaltung von Projekten und Programmen. An der Ausbildung waren auch mehrere Akteure aus dem akademischen und beruflichen Umfeld beteiligt. Dies erm\u00f6glichte eine viel professionellere und praktischere und vor allem angewandte Ausbildung mit mehreren sehr fortschrittlichen Instrumenten f\u00fcr eine rigorose Bewertung der \u00f6ffentlichen Politik, Projekte und Programme sowohl quantitativ als auch qualitativ. Die Ausbildung konzentrierte sich auf praktische F\u00e4lle und reale Beispiele f\u00fcr die Evaluierung von \u00f6ffentlichen Politiken, Projekten und Programmen sowohl in der Schweiz als auch auf internationaler Ebene. Sie hat mir eine gute Kenntnis der verschiedenen Evaluationsmodelle und vor allem eine gute Dosis des wissenschaftlichen Ansatzes in der Evaluation erm\u00f6glicht. Dies erm\u00f6glicht es mir, nach der Durchf\u00fchrung von Evaluationen von \u00f6ffentlichen Politiken, Projekten und Programmen sehr relevante Empfehlungen f\u00fcr die Entscheidungshilfe im privaten wie auch im \u00f6ffentlichen Sektor zu formulieren. Ich konnte an der praktischen Evaluierung eines Programms f\u00fcr internationale Zusammenarbeit und Entwicklung arbeiten.<\/em><\/p>\n<h6>&#8211; Wie sehen Sie Ihre Zukunft in der Schweizer Evaluationsgemeinschaft?<\/h6>\n<p><em>Eine erf\u00fcllte berufliche Zukunft in dieser Gemeinschaft. Mit dieser Ausbildung, kombiniert mit meinen Berufserfahrungen in der Projekt- und Programmevaluation, werde ich in einer sehr guten Position sein f\u00fcr Evaluationsmandate von internationalen Originationen f\u00fcr soziale, \u00f6kologische und Entwicklungsfragen. Mit der SEVAL ist es eine kontinuierliche Ausbildung mit der Ber\u00fccksichtigung neuer Forschungsergebnisse zu Evaluationen \u00f6ffentlicher Politiken. Dies erm\u00f6glicht eine perfekte Beherrschung nicht nur von Fragen der Evaluation von Wirtschafts- und Sozialpolitiken auf Schweizer Ebene, sondern auch von Fragen der internationalen Zusammenarbeit und Entwicklung, die auf die grossen Entwicklungsprojekte und -programme der Schweizer Politik im Ausland ausgerichtet sind. Es ist auch eine gute Gelegenheit, sich in ein gro\u00dfes globales Netzwerk von Fachleuten und Experten f\u00fcr die Evaluation von \u00f6ffentlichen Politiken, Projekten und Programmen zu integrieren, um so die Expertise in der Evaluation zu st\u00e4rken und aufzubauen.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h3><a id=\"absatz_2\"><\/a>Internationales<\/h3>\n<hr \/>\n<h5><b>Bericht<\/b><\/h5>\n<h4><b>IV. Weltforum f\u00fcr Evaluation<\/b><\/h4>\n<p>Rabat &#8211; 26., 27. und 28. Februar 2024<\/p>\n<p>Das IV. Weltforum f\u00fcr Evaluation mit dem Titel &#8221; <a href=\"https:\/\/www.evalforward.org\/events\/evalpartners-iv-global-evaluation-forum-leading-progressive-contemporary-evaluation-practice\" target=\"_blank\" rel=\"noopener\">F\u00fchren einer progressiven und zeitgem\u00e4\u00dfen Evaluationspraxis<\/a> &#8221; fand vom 26. bis 28. Februar in Rabat, Marokko, statt.<\/p>\n<p>Das Forum wurde von der Internationalen Organisation f\u00fcr die Zusammenarbeit in der Evaluation (OICE) und EvalPartners in Zusammenarbeit mit der Association Marocaine d&#8217;\u00c9valuation (AME), den UN-Organisationen sowie dem finnischen Au\u00dfenministerium und dem Deutschen Institut f\u00fcr Entwicklungsevaluation (DeVAL) organisiert. Das Forum wurde haupts\u00e4chlich in englischer Sprache abgehalten, in geringerem Ma\u00dfe auch in Franz\u00f6sisch und Arabisch.<\/p>\n<p>Das IV. Weltforum f\u00fcr Evaluation bot EvalPartners und der globalen Evaluationsgemeinschaft die Gelegenheit, eine neue EvalAgenda 2030 zu erarbeiten, die Evaluation zu vertiefen und voranzutreiben, einschlie\u00dflich der Erweiterung und Optimierung von Partnerschaften und der Umsetzung der UN-Resolution (A\/RES\/77\/283) f\u00fcr die nationale Evaluierung der Ziele f\u00fcr nachhaltige Entwicklung (SDGs), die 2023 verabschiedet werden soll.<\/p>\n<p>Am Montag fanden parallel dazu <b>Vorforen-Workshops<\/b> zu eher <b>methodischen<\/b> Aspekten statt:<\/p>\n<ul>\n<li>Vom Land durchgef\u00fchrte Evaluation: Maximierung des Nutzens, der Verwendung und der Qualit\u00e4t.<\/li>\n<li>Evaluierung, um nationale Priorit\u00e4ten mit den SDGs zu verkn\u00fcpfen.<\/li>\n<li>Die Rolle von VOPEs (Voluntary Organizations for Professional Evaluation) bei der F\u00f6rderung der UN-Resolution.<\/li>\n<li>Welche Antworten gibt es auf die methodischen Herausforderungen bei der Evaluierung \u00f6ffentlicher Politiken?<\/li>\n<li>Wie lassen sich die Klippen der Standardisierung umschiffen? Methodische Grundlagen f\u00fcr eine gr\u00f6\u00dfere Vielfalt in der Evaluation.<\/li>\n<li>Transformative, progressive und innovative Evaluierungspraktiken.<\/li>\n<li>Analyse von Beitr\u00e4gen: Rahmen f\u00fcr die Evaluierung und Vermeidung von Fallstricken.<\/li>\n<li>Generative k\u00fcnstliche Intelligenz (GI)<\/li>\n<\/ul>\n<p>Am Dienstag nahmen an<b> der Er\u00f6ffnungsplenarsitzung<\/b> marokkanische Offizielle teil. Dabei ergaben sich die folgenden Hauptelemente:<\/p>\n<ul>\n<li>Die Bedeutung der Evaluierung f\u00fcr die parlamentarische Rechenschaftspflicht und die evidenzbasierte Entscheidungsfindung.<\/li>\n<li>Die Notwendigkeit eines partizipativen Ansatzes, der die Stimme der B\u00fcrgerinnen und B\u00fcrger in den Evaluierungsprozess einbezieht.<\/li>\n<li>Die Herausforderungen im Zusammenhang mit der Datenqualit\u00e4t und den begrenzten Ressourcen, die die Wirksamkeit der Evaluierung behindern.<\/li>\n<li>Der Wert der Institutionalisierung der Evaluierung in den Mechanismen der Regierungsf\u00fchrung und der Entscheidungsfindung.<\/li>\n<li>Die Verpflichtung zur kontinuierlichen Verbesserung und Anpassung von Evaluierungsmethoden, um den sich st\u00e4ndig \u00e4ndernden Bed\u00fcrfnissen gerecht zu werden.<\/li>\n<\/ul>\n<p>Die Plenardiskussion befasste sich mit der <b>Transformation der Evaluierung<\/b>, um globalen und nationalen Realit\u00e4ten Rechnung zu tragen. Daraus ging hervor:<\/p>\n<ul>\n<li>Die Wichtigkeit, systemische Ans\u00e4tze und transformative Theorien des Wandels zu \u00fcbernehmen.<\/li>\n<li>Die Notwendigkeit einer inklusiveren und partizipativeren Evaluierung.<\/li>\n<li>Das Potenzial von Technologie und Innovation zur Bereicherung der Evaluierung.<\/li>\n<li>Die Herausforderungen f\u00fcr die Transformation der Evaluation und Strategien zu ihrer Bew\u00e4ltigung.<\/li>\n<li>Die Chancen, die sich durch eine verst\u00e4rkte internationale Zusammenarbeit und eine globale Perspektive ergeben.<\/li>\n<\/ul>\n<p>Die <b>Parallelsitzungen<\/b> am Nachmittag befassten sich insgesamt mit drei Themenbereichen:<\/p>\n<ul>\n<li>Mehrere befassten sich mit den <b>Zielen f\u00fcr nachhaltige Entwicklung<\/b>:<br \/>\no Evaluation der SDGs und St\u00e4rkung der Evaluierungskapazit\u00e4ten der Regierung.<br \/>\no Der Wert der Evaluierung in einer Welt im Wandel: Auswirkungen auf die Erreichung der SDGs im Rahmen einer l\u00e4ndergef\u00fchrten Entwicklung.<br \/>\no Nationale Evaluation der SDGs: Ein dringender Aufruf zum Handeln.<br \/>\no Freiwillige nationale Pr\u00fcfungen und Geschlechtergleichstellung: Wo sind die Beweise?<\/li>\n<li>Eine Sitzung befasste sich mit der <b>Rolle der Parlamentarier bei der Institutionalisierung<\/b> der Politikevaluation. Sechs Jahre nach der Colombo-Erkl\u00e4rung befasste sich die Sitzung mit den Ma\u00dfnahmen, die Parlamente auf der ganzen Welt zur Umsetzung der Colombo-Erkl\u00e4rung und zur Institutionalisierung der Evaluierung ergriffen haben, mit den erzielten Ergebnissen, den Herausforderungen und den gelernten Lektionen.<\/li>\n<li>Zwei Sitzungen befassten sich mit <b>Dekolonisierung<\/b> \/ S\u00fcd-S\u00fcd-Beziehungen:<br \/>\no Dekolonisierung der Evaluierungspraxis.<br \/>\no S\u00fcd-S\u00fcd-Richtlinien f\u00fcr eine transformative Evaluierung.<\/li>\n<\/ul>\n<p>Am letzten Tag war eine Plenardiskussion \u00fcber <b>die Richtung der EvalAgenda 2030<\/b> geplant. Vertreterinnen und Vertreter von UN-Organisationen und Geberorganisationen (UNSDG, Unicef, UNFPA) und anderen internationalen Institutionen (EvalPartners, IEAC) \u00fcberpr\u00fcften die Rolle der Evaluation angesichts der zeitgen\u00f6ssischen Herausforderungen und versuchten, eine neue Richtung einzuschlagen, um einen wirksamen Beitrag zur Erreichung der SDGs zu leisten. Das Panel betonte die Dringlichkeit innovativer und handlungsorientierter Evaluationsans\u00e4tze, um die globalen Bem\u00fchungen zur Erreichung der SDGs zu unterst\u00fctzen.<\/p>\n<p>Sowohl die Podiumsteilnehmer als auch das Forumspublikum betrachten Evaluation insgesamt nicht nur als Messinstrument und zur Unterst\u00fctzung der Entscheidungsfindung, sondern vielmehr als Katalysator f\u00fcr Ver\u00e4nderungen, als Mittel, um den Stimmlosen eine Stimme zu verleihen, und als Pfeiler f\u00fcr den Aufbau widerstandsf\u00e4higerer und inklusiverer Gesellschaften, wof\u00fcr die EvalAgenda 2030 ein Symbol darstellt.<\/p>\n<p>Auch an diesem letzten Tag wurden parallel <b>Sitzungen<\/b> abgehalten:<\/p>\n<ul>\n<li>Eine befasste sich mit den Lehren, die aus den Erfahrungen mit der Institutionalisierung von Evaluierungskapazit\u00e4ten und -funktionen auf globaler Ebene gezogen werden k\u00f6nnen.<\/li>\n<li>Eine andere versuchte, eine Bilanz nach acht Jahren seit der Einf\u00fchrung der SDGs zu ziehen.<\/li>\n<li>Ein Panel befasste sich mit der Frage, inwieweit ein Evaluierungsansatz Made in Africa auf andere Regionen \u00fcbertragbar ist.<\/li>\n<\/ul>\n<p>Eine letzte Plenumsdiskussion befasste sich mit <b>der UN-Resolution<\/b>, dem Weg zur Umsetzung und dem Handeln entsprechend der Resolution und der Rolle der verschiedenen Akteure, um diese voranzutreiben.<\/p>\n<p>Schlie\u00dflich befasste sich ein letztes <b>Panel<\/b> mit der <b>Professionalisierung der Evaluation<\/b>. Organisiert und moderiert von Claudine Morier, Mitglied der SEVAL, vier Jahre lang Vizepr\u00e4sidentin des RFE, jetzt neue Vertreterin des RFE bei der OICE, versammelte dieses Panel Vertreterinnen und Vertreter nationaler Evaluationsverb\u00e4nde aus Luxemburg, dem Senegal, Marokko und Mexiko. Das Panel befasste sich mit der Notwendigkeit der Professionalisierung der Evaluation (warum) sowie mit den organisatorischen und praktischen Prozessen und Modalit\u00e4ten (wie).<\/p>\n<p>Es beleuchtete verschiedene Erfahrungen und gelernte Lektionen in dem f\u00fcr jedes Land einzigartigen Prozess hin zu einer strukturierteren und professionalisierten Evaluierung. Durch die Behandlung konkreter Beispiele und bew\u00e4hrter Strategien veranschaulichte das Panel die Diskussionen, die heute die Evaluationsgemeinschaft bewegen. Die Herausforderungen bei der Institutionalisierung von Evaluationskapazit\u00e4ten sind zahlreich, darunter der Widerstand gegen Ver\u00e4nderungen, fehlende Ressourcen und die Spannung zwischen individuellen versus systemischen F\u00e4higkeiten. Es gibt jedoch M\u00f6glichkeiten, einigen dieser Herausforderungen teilweise entgegenzuwirken, wie z.B. technologische Innovation, internationale Zusammenarbeit \u00fcber Netzwerke wie insbesondere das RFE und die F\u00f6rderung einer Kultur des Lernens und der kontinuierlichen Verbesserung.<\/p>\n<p><b>Meine Meinung zum Forum<\/b><\/p>\n<p>Ich nahm zum ersten Mal an diesem Forum teil, das von internationalen und UNO-Organisationen getragen wird, die EvaluatorInnen in der Entwicklungszusammenarbeit seit langem kennen.<\/p>\n<p>Das erste, was mir auffiel, war, dass wir zwar \u00fcber die gleiche Disziplin sprachen, teilweise die gleichen Methoden anwendeten (mit Ausnahme der quasi-experimentellen Wirkungsevaluationen, die diesem Bereich eigen sind, und anderer Methoden, die in der Schweiz kaum angewendet werden, wie zum Beispiel die Beitragsanalyse oder das Outcome Harvesting) und die gleichen Kriterien verwendeten, dass sich aber der Ansatz als sehr unterschiedlich erwies. Die Debatten waren gepr\u00e4gt von alarmierenden und interventionistischen Beitr\u00e4gen. Die Evaluatoren in der Entwicklungszusammenarbeit sind der Ansicht, dass sie eine Rolle bei der Festlegung und Umsetzung der nationalen und internationalen \u00f6ffentlichen Politik zu spielen haben und f\u00fchlen sich teilweise verantwortlich f\u00fcr das Scheitern bei der Erreichung der SDGs, um die sich die gesamte Veranstaltung drehte.<\/p>\n<p>Zweitens war die geringe Beteiligung (ca. 100 Teilnehmer\/innen) der Veranstaltung nicht angemessen. An europ\u00e4ischen oder afrikanischen Konferenzen nehmen beispielsweise vier- bis f\u00fcnfmal so viele Menschen teil. Dies ist unter anderem auf Finanzierungsschwierigkeiten zur\u00fcckzuf\u00fchren, die einen Wandel verdeutlichen, der in den letzten Jahren auf globalerer Ebene bei vielen regionalen und internationalen Organisationen zu beobachten war. Dies hat zu einer gewissen Isolation sowie zu einer Unsichtbarmachung der VOPEs gef\u00fchrt.<\/p>\n<p>Letztendlich war meine Teilnahme dennoch eine Bereicherung. Auch wenn Vergleiche nicht gerechtfertigt sind, ist das frankophone Evaluationsnetzwerk auf allen Ebenen gest\u00e4rkt worden. Die F\u00e4higkeit des RFE, Schl\u00fcsselpersonen zu mobilisieren, seine Professionalit\u00e4t bei der Organisation des Internationalen Frankophonen Evaluationsforums und der Mehrwert der f\u00fcr seine Mitglieder entwickelten Instrumente, wie das Diagnoseinstrument im Bereich der Professionalisierung, zeigen die Relevanz des Engagements der SEVAL in diesem Netzwerk. Es liegt auf der Hand, dass die Zusammenarbeit mit Partnern aus demselben Sprachraum die Dinge erleichtert, auch wenn die kulturellen Unterschiede zwischen den drei im RFE zusammengeschlossenen Kontinenten enorm sind. Die Zusammenarbeit auf globaler Ebene ist in der Tat noch schwieriger und ehrgeiziger, und die Teilnahme an einer solchen Veranstaltung ist wahrscheinlich eher f\u00fcr Personen gedacht, die in der Entwicklungsevaluation t\u00e4tig sind.<\/p>\n<p>Claudine Morier<br \/>\nMitbegr\u00fcnderin von <a href=\"https:\/\/laoulia.com\/\" target=\"_blank\" rel=\"noopener\">laoulia<\/a><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p><strong>Die Webseiten der Evaluationsgesellschaften in der Schweiz und weltweit finden Sie <a href=\"https:\/\/www.seval.ch\/publikationen-prix-seval\/publikationen\/links\/\" target=\"_blank\" rel=\"noopener\">hier\u00a0<\/a><br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h3><a id=\"absatz_3\"><\/a>Aus- und Weiterbildung<\/h3>\n<hr \/>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-16425\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image16-300x94.jpg\" alt=\"\" width=\"300\" height=\"94\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image16-300x94.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image16.jpg 374w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4><strong>Einladung zu \u00f6ffentlichen Veranstaltungen im Rahmen des International Program for Development Evaluation Training (IPDET) an der Universit\u00e4t Bern<\/strong><\/h4>\n<p>Das renommierte internationale Fortbildungsprogramm in Evaluation wird vom 15. bis 26. Juli 2024 an der Uni Bern stattfinden. Wir erwarten \u00fcber 180 Teilnehmende aus ca. 65 L\u00e4ndern, die gemeinsam zu den Grundlagen in Evaluation und zu aktuellen Evaluationsthemen lernen, sich austauschen und networken. Interessierte sind herzlich zu folgenden <strong>\u00f6ffentlichen Veranstaltungen<\/strong> eingeladen:<\/p>\n<p><strong>15.7., 9:00-10:30h: IPDET Opening <\/strong><\/p>\n<p>Der Stadtpr\u00e4sident, Alec von Graffenried, wird das IPDET onsite Programm 2024 offiziell er\u00f6ffnen. Erfahren Sie mehr zu den Teilnehmenden und zum <em>Core Course on Fundamentals of Evaluation<\/em>, mit dem das Programm startet. In der anschliessenden Kaffepause besteht die M\u00f6glichkeit des Kennlernens und des Austauschs mit den Teilnehmenden und Dozierenden.<\/p>\n<p><strong>17.7., 18:30-19:30h: Impact Happy Hour<\/strong><\/p>\n<p>Informeller Austausch organisiert von <a href=\"https:\/\/urldefense.com\/v3\/__https:\/www.cooperationglobale.ch\/__;!!Dc8iu7o!yhzz3p0Rowl6LjSn4tHXzlQ-H4q-FOiH0AzUqDDJNWakE-IwviMPHzXYzxkAHMAIA8QWbAWkrVGoAylbBKdg-_0CRKD1jk8pdQ2hKA$\">Coop\u00e9ration Globale: Starke Armutsbek\u00e4mpfung &#8211; starke Schweiz (cooperationglobale.ch)<\/a> zu Evaluation und Wirkungsmessung \u00fcber die Entwicklungszusammenarbeit hinaus. Diskussion zu H\u00fcrden, Best Practices und Unterst\u00fctzungsm\u00f6glichkeiten durch Coop\u00e9ration Globale.<\/p>\n<p><strong>24.07., 14:00-15:00h: Fishbowl Discussion on the <\/strong><strong>Institutionalisation of Evaluation in a Global Perspective &#8211; Results from Europe, North- and South America, and Asia <\/strong><\/p>\n<p>Im Anschluss Kaffee und Kuchen im Garten und IPDET World Exhibition mit Items aus den verschiedenen Kulturen und L\u00e4ndern der Teilnehmenden.<\/p>\n<p><strong>25.07., 19:00-20:00h: Open Forum on Evaluating Humanitarian Action <\/strong>organized by the Ukrainian Evaluation Association (UEA) and the Active Learning Network for Accountability and Performance in Humanitarian Action (ALNAP).<\/p>\n<p>Schauen Sie vorbei, diskutieren Sie mit und erleben den einmaligen Spirit von IPDET!<\/p>\n<p><u>Ort<\/u>: Universit\u00e4t Bern, Zentrum f\u00fcr universit\u00e4re Weiterbildung, Geb\u00e4ude UniS, Schanzeneckstr. 1, Auditorium S003, Bern<\/p>\n<p><u>Kontakt<\/u>: Dr. Stefanie Krapp, Head of IPDET, <a href=\"&#109;&#x61;&#x69;&#108;&#x74;&#x6f;:&#x73;&#x74;e&#102;&#x61;n&#105;&#x65;&#46;&#107;&#x72;a&#112;&#x70;&#64;&#117;&#x6e;&#x69;&#98;&#x65;&#x2e;&#99;&#x68;\">&#115;t&#x65;f&#x61;n&#x69;&#101;&#x2e;&#107;&#x72;&#97;p&#x70;&#64;&#x75;n&#x69;&#98;&#x65;&#46;&#x63;&#104;<\/a><\/p>\n<hr \/>\n<h4>Der n\u00e4chste CAS Evaluation startet im M\u00e4rz 2025<\/h4>\n<h3>am Zentrum f\u00fcr universit\u00e4re Weiterbildung (ZUW) der Universit\u00e4t Bern!<\/h3>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16426 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image17-300x225.jpg\" alt=\"\" width=\"368\" height=\"276\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image17-300x225.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image17.jpg 315w\" sizes=\"(max-width: 368px) 100vw, 368px\" \/><\/p>\n<p>Absolventinnen und Absolventen des CAS Evaluation 2023 beim Abschlusstag<\/p>\n<p>Der <strong>CAS Evaluation<\/strong> richtet sich an Personen, die Evaluationen in Auftrag geben oder das Management von Evaluationen verantworten. Struktur, Inhalte und didaktische Formate wurden f\u00fcr die Durchf\u00fchrung 2025 \u00fcberarbeitet. Behandelt werden grundlegende Fragen wie, was ist Evaluation und wodurch zeichnet sie sich gegen\u00fcber anderen Ans\u00e4tzen aus, welche Schritte beinhaltet eine Evaluation und was geh\u00f6rt zum Management von Evaluationsprojekten, was sind Wirkungsmodelle und welche Rolle spielen sie bei Evaluationen, welche Designs und Erhebungsmethoden k\u00f6nnen bei Evaluationen eingesetzt werden, was macht eine gute Evaluation aus und wie kann deren Nutzung bef\u00f6rdert werden?<\/p>\n<p>Der CAS Evaluation dauert ein Jahr (M\u00e4rz 2025 bis M\u00e4rz 2026), umfasst 7 Module und einen Abschlusstag. Es werden 15 ECTS-Punkte vergeben. Die CAS Arbeit ist auf einen m\u00f6glichst hohen praktischen Anwendungsnutzen f\u00fcr die Teilnehmenden ausgerichtet.<\/p>\n<p>Weitere Informationen und Anmeldung: <a href=\"https:\/\/www.unibe.ch\/weiterbildungsangebote\/cas_evaluation\/index_ger.html\" target=\"_blank\" rel=\"noopener\">HIER<\/a><br \/>\nKontakt: Dr. Stefanie Krapp, Bereichsleitung Evaluation am ZUW, <a href=\"&#109;&#x61;i&#108;&#x74;o&#58;&#x73;t&#x65;&#x66;&#97;&#x6e;i&#101;&#x2e;k&#114;&#x61;p&#x70;&#x40;&#117;&#x6e;&#x69;&#98;&#x65;&#46;&#99;&#x68;\">&#x73;t&#x65;&#102;&#x61;&#110;&#x69;&#x65;&#46;&#x6b;&#114;&#x61;&#112;&#x70;&#64;u&#x6e;&#105;&#x62;&#101;&#x2e;&#99;h<\/a><\/p>\n<p>Nachwuchsevaluator:innen: Die SEVAL vergibt gemeinsam mit dem ZUW ein Stipendium f\u00fcr die Teilnahme am CAS: <a href=\"https:\/\/www.seval.ch\/stipendium-prix-seval\/seval-stipendium\/\" target=\"_blank\" rel=\"noopener\">Stipendium \u2013 SEVAL<\/a><\/p>\n<p><strong>Das sagen Absolvent:innen des CAS 2023:<\/strong><br \/>\n<em>\u00abIm CAS haben wir den Evaluationsprozess aus unterschiedlichen Perspektiven beleuchtet und die Umsetzung der theoretischen Grundlagen in die konkrete Praxis erlernt. So kann ich das Gelernte direkt in meiner Arbeit anwenden\u00bb, <\/em>Julia Rickenbacher, interface<br \/>\n<em>\u00abAlle wollen Wirkung, und doch begn\u00fcgen sich die meisten mit guter Hoffnung statt Evidenz. Der CAS-Kurs hat mir Wege gezeigt, der Wirkung nachzusp\u00fcren\u00bb<\/em>, Philip Gehri, DVIGS<\/p>\n<hr \/>\n<h3>Weiterbildungskurs im flipped classroom Format zu den<br \/>\n<a href=\"https:\/\/zuw.me\/kurse\/dt.php?kid=4704\" target=\"_blank\" rel=\"noopener\">Grundlagen von Evaluationen f\u00fcr die eigene Berufspraxis, 31.10., 21.11., 12.12.2024<\/a><\/h3>\n<h6>Zentrum f\u00fcr universit\u00e4re Weiterbildung (ZUW) der Universit\u00e4t Bern in Kooperation mit der Eidgen\u00f6ssischen Hochschule f\u00fcr Berufsbildung (EHB)<\/h6>\n<p>Evaluationen &#8211; jenseits von Ritualen, automatisierten Kontrollmechanismen und standardisierten Qualit\u00e4tsmanagementprozessen &#8211; bringen hohen Nutzen z. B. f\u00fcr Entwicklungs-, Lern- und Lehrprozesse. Der Kurs zeigt auf, wie dieses Versprechen durch seri\u00f6se und realistische Evaluationsplanung, abgestimmt auf spezifische Bed\u00fcrfnisse und Informationsinteressen, eingehalten werden kann.<\/p>\n<p>Der Kurs folgt dem didaktischen Konzept des \u00abinverted classroom\u00bb (flipped classroom). D.h. die Inhalte werden zuhause erarbeitet, die praktische Anwendung erfolgt an den 3 Pr\u00e4senztagen. Der Kurs ist f\u00fcr den CAS Evaluation anrechenbar.<\/p>\n<p>Weitere Informationen und Anmeldung: <a href=\"https:\/\/zuw.me\/kurse\/dt.php?kid=4704\" target=\"_blank\" rel=\"noopener\">HIER<\/a><br \/>\nDozierende: Prof. Dr. Lars Balzer, Dr. Veronique Eicher (EHB)<br \/>\nKontakt: Dr. Stefanie Krapp, Bereichsleitung Evaluation am ZUW, <a href=\"&#109;&#x61;i&#108;&#x74;o&#58;&#x73;t&#x65;&#x66;&#97;&#x6e;i&#101;&#x2e;k&#114;&#x61;p&#x70;&#x40;&#117;&#x6e;&#x69;&#98;&#x65;&#46;&#99;&#x68;\">&#x73;t&#x65;&#102;&#x61;&#x6e;i&#x65;&#46;&#x6b;&#x72;a&#x70;&#112;&#x40;&#x75;n&#x69;&#98;&#x65;&#x2e;c&#x68;<\/a><\/p>\n<hr \/>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-16443\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image29-300x196.jpg\" alt=\"\" width=\"300\" height=\"196\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image29-300x196.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image29.jpg 645w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h4>The International Program for Development Evaluation Training (IPDET) at the University of Bern<\/h4>\n<h6>This is IPDET<\/h6>\n<p>The International Program for Development Evaluation Training (IPDET) is an executive training program that aims to provide decision makers, managers and practitioners with the tools and skills to commission, manage and implement policy, program or project evaluations at local, national, regional, and global levels as well as to use those evaluations for decision-making. IPDET sets a great focus on practice and provides a diversified approach for audiences from different organizations and sectors who play different roles in the evaluation process. This is unique in the evaluation training sector and gives the participants differentiated perspectives on evaluation and connects individuals worldwide.<br \/>\nThe program is a collaborative effort between three partners: The Center for Continuing Education (ZUW) at the University of Bern, Switzerland, the Center for Evaluation (CEval) in Saarbr\u00fccken, Germany, and the Independent Evaluation Group of the World Bank (IEG). This partnership brings long-standing roots in development evaluation and training as well as strong faculty with on-the-ground experience.<br \/>\nSince 2021, IPDET is a core implementing partner of the <a href=\"https:\/\/www.globalevaluationinitiative.org\/\" target=\"_blank\" rel=\"noopener\">Global Evaluation Initiative (GEI)<\/a> and receives funds especially for scholarships and Global Outreach activities from GEI funding partners. GEI is an inclusive global partnership committed to developing country-owned, sustainable monitoring and evaluation (M&amp;E) frameworks and capacities to promote the use of evidence in public decision-making, enhance accountability, and achieve better results.<br \/>\nBased on IPDET\u00b4s <a href=\"https:\/\/ipdet.org\/wp-content\/uploads\/2021\/04\/IPDET-ECD-Strategy-Paper.pdf\" target=\"_blank\" rel=\"noopener\">Evaluation Capacity Development Strategy<\/a>, IPDET consists of three different streams of capacity building activities, which are framed by overarching community building activities:<br \/>\nOn-Site Program | Bern, Switzerland | Fundamentals of evaluation are taught during the one-week Core Course, followed by one week of consolidation and specialized workshops. Furthermore, due to its onsite character, it is a central networking place for the IPDET Community.<img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-16428 alignright\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image19-300x261.jpg\" alt=\"\" width=\"300\" height=\"261\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image19-300x261.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image19-768x668.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image19.jpg 879w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><br \/>\n<strong>Online Workshops |<\/strong> Adapting to the constrains of the Covid-19 pandemic IPDET developed an online program stream in 2020. Each workshop is conducted throughout one week and covers a specialized evaluation topic. The online workshops combine synchronous and asynchronous learning.<br \/>\n<strong>Global Outreach |<\/strong> Since 2021 IPDET is expanding its activities across the globe, guided by its IPDET\u2019s <a href=\"https:\/\/ipdet.org\/wp-content\/uploads\/2021\/06\/IPDET_GlobalOutreachStrategy.pdf\" target=\"_blank\" rel=\"noopener\">Global Outreach Strategy<\/a>, ensuring that trainings and guidance can better be tailored to the needs of specific audiences in different regions. The activities are both, demand and supply driven and target decision makers and practitioners in national governments, civil society and development organizations, parliamentarians and their scientific staff, trainers for evaluation, and young and emerging evaluators.<br \/>\n<strong>Community Building |<\/strong> To strengthen and connect the community, IPDET engages the onsite participants in specific networking activities and implements online activities, like the Kick-Off and Closing Event, social gatherings, and technical tools, like the IPDET Listserv, the IPDET eLearning platform, and the IPDET CoSMOS (Community server \u2013 a memorable online society).<\/p>\n<h6>IPDET`s 2023 participants<\/h6>\n<p><strong>Participation numbers |<\/strong> The IPDET On-Site program 2023 attracted 171 individuals in total, 76 of them have been awarded a scholarship. During the first week, a total of 119 participants attended the Core Course and for the second week IPDET welcomed 146 participants who attended one to two workshops.<br \/>\n<strong>Countries and regions |<\/strong> Participants coming from \u2018Europe and Central Asia\u2019 accounted for the highest attendance share during the entire On-Site program (35%), and especially during the workshop week. In the Core Course they were closely followed by participants from Sub-Saharan Africa.<br \/>\nParticipants came from <strong>70 different countries<\/strong>:<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16429 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image20-300x187.jpg\" alt=\"\" width=\"369\" height=\"230\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image20-300x187.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image20-1024x639.jpg 1024w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image20-768x479.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image20-1320x823.jpg 1320w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image20.jpg 1382w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p>Table 1: Countries with highest attendance in 2023 (onsite and online)<br \/>\n<strong>Job Position in M&amp;E |<\/strong> Regarding the job position that participants held at the time of the On-Site program it can be stated that half of the participants worked as \u2018M&amp;E Officers or Specialists\u2019, while the second largest category was represented by those working as a \u2018Program\/Project Officer or Manager\u2019 (14%). The third largest group was \u2018M&amp;E Unit Managers\u2019 (11%). A small proportion of the overall participants reported working as a \u2018Consultant\u2019 (8%) or a \u2018Researcher\/Evaluator at a University\/Think Tank\u2019 (6%), and even fewer participants (only 5%) indicated to be working as \u2018Decision Maker at the Upper Management Level\u2019.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-16430\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image21-1024x544.jpg\" alt=\"\" width=\"601\" height=\"319\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image21-1024x544.jpg 1024w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image21-300x159.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image21-768x408.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image21.jpg 1211w\" sizes=\"(max-width: 601px) 100vw, 601px\" \/><\/p>\n<p>Figure 2: Job positions of participants<br \/>\n<strong>Type of organization |<\/strong> 27% of participants worked for the \u2018Government, Ministry, Agency or Bureau\u2019, representing the largest categorical group; followed by those from an \u2018UN\/UN specialized agency\u2019 (17%), a \u2018Non-governmental organization\u2019 (16%), and a \u2018Financial institution\u2018 (13%).<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-16431\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image22.jpg\" alt=\"\" width=\"599\" height=\"314\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image22.jpg 1220w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image22-300x157.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image22-1024x536.jpg 1024w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image22-768x402.jpg 768w\" sizes=\"(max-width: 599px) 100vw, 599px\" \/><\/p>\n<p>Figure 3: Types of organizations participants are working for<\/p>\n<h6>IPDET`s take aways and plans to utilize the gained knowledge<\/h6>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-16432 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image23-242x300.jpg\" alt=\"\" width=\"242\" height=\"300\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image23-242x300.jpg 242w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image23.jpg 297w\" sizes=\"(max-width: 242px) 100vw, 242px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-16436 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image27-300x127.jpg\" alt=\"\" width=\"300\" height=\"127\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image27-300x127.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image27-1024x435.jpg 1024w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image27-768x326.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image27.jpg 1239w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-16437 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image28-300x134.jpg\" alt=\"\" width=\"300\" height=\"134\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image28-300x134.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image28-1024x456.jpg 1024w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image28-768x342.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image28.jpg 1132w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16433 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image24-300x168.jpg\" alt=\"\" width=\"369\" height=\"207\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image24-300x168.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image24-768x430.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image24.jpg 945w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p style=\"text-align: center;\">And or enroll in this year`s online workshop:<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"alignnone wp-image-16435 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image26-300x187.jpg\" alt=\"\" width=\"369\" height=\"230\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image26-300x187.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image26.jpg 493w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p>More information: International Program for Development Evaluation Training | IPDET<br \/>\nContact: Dr. Stefanie Krapp, Head of Program, &#x73;&#116;e&#x66;&#97;&#110;&#x69;&#x65;&#46;k&#x72;&#97;p&#x70;&#x40;&#117;n&#x69;&#98;e&#x2e;&#x63;&#104;<\/p>\n<hr \/>\n<p>Weitere Veranstaltungen finden Sie auf unserer <a href=\"https:\/\/www.seval.ch\/news-veranstaltungen\/weitere-veranstaltungen\/\" target=\"_blank\" rel=\"noopener noreferrer\">SEVAL-Webseite\u00a0<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><a id=\"absatz_4\"><\/a>Informationen aus den Arbeitsgruppen<\/h3>\n<hr \/>\n<h4><strong>SEVAL Erfahrungsaustausch zur Wirksamkeit der <\/strong><strong>internationalen Zusammenarbeit<\/strong><\/h4>\n<h6><strong> 29. Februar 2024 am Zentrum f\u00fcr universit\u00e4re Weiterbildung (ZUW) der Uni Bern<\/strong><\/h6>\n<p>Die SEVAL Arbeitsgruppen Internationale Zusammenarbeit und Kompetenzen haben gemeinsam mit der Eidgen\u00f6ssischen Finanzkontrolle (EFK) am 29.02.2024 einen spannenden Austausch organisiert mit:<\/p>\n<ul>\n<li>Dr. J\u00f6rg Faust, Direktor des Deutschen Evaluierungsinstitutes der Entwicklungszusammenarbeit (DEval)<\/li>\n<li>Simone Ledermann, Leiterin der Parlamentarischen Verwaltungskontrolle der Schweiz (PVK)<\/li>\n<li>Silvana Hogg, Leiterin der Fachstelle Evaluation und Controlling der DEZA<\/li>\n<li>Reto Th\u00f6nen, Fachstelle Evaluation und Controlling der DEZA<\/li>\n<li>Stefanie Krapp, Leiterin des International Program for Development Evaluation Training (IPDET) der Uni Bern<\/li>\n<\/ul>\n<p>Die hohe Zahl an Teilnehmenden an der Veranstaltung mit 45 Personen zeigt das grosse Interesse am Thema Wirksamkeit der IZ.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16410 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image1.jpg\" alt=\"\" width=\"365\" height=\"274\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image1.jpg 365w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image1-300x225.jpg 300w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/p>\n<p style=\"text-align: center;\">Von links nach rechts: Stefanie Krapp (IPDET \/ Uni Bern), J\u00f6rg Faust (DEval), Silvana Hogg (DEZA), Simone Ledermann (PVK), Reto Th\u00f6nen (DEZA), Kimon Schneider (NADEL ETHZ), Mathias Rickli (EFK), Laurent Cremieux (SEVAL \/ EFK).<\/p>\n<h5><strong>1. Die Rolle des Deutschen Evaluierungsinstituts der Entwicklungszusammenarbeit (DEval) <\/strong><\/h5>\n<p>Nach der Begr\u00fcssung des SEVAL Vorstandsvertreters Laurent Cremieux und der Einf\u00fchrung durch Stefanie Krapp (ZUW\/Uni Bern) und Mathias Rickli (EFK), hat J\u00f6rg Faust in einem Inputreferat zur <strong>Entstehung, den Zielen und dem Zweck des DEval und seinem Nutzen f\u00fcr die \u00d6ffentlichkeit<\/strong> berichtet. Das DEval wurde 2012 vom Bundesministerium f\u00fcr wirtschaftliche Zusammenarbeit und Entwicklung (BMZ) gegr\u00fcndet. Kernaufgabe des DEval ist es, die Aktivit\u00e4ten der deutschen Entwicklungszusammenarbeit zu analysieren und zu bewerten \u2013 unabh\u00e4ngig, praxisorientiert und auf der Grundlage wissenschaftlicher Erkenntnisse. Damit agiert das Institut an der Schnittstelle von Politik, Wissenschaft und Praxis mit dem \u00fcbergeordneten Ziel, der Entwicklungszusammenarbeit n\u00fctzliche Evidenz zur Verf\u00fcgung zu stellen. Eine weitere Aufgabe besteht darin, die vorhandenen Methoden und Standards der Evaluierung weiterzuentwickeln, um die Evaluierungspraxis zu verbessern. Zudem arbeitet das DEval daran, die Evaluierungskapazita\u0308ten in den Partnerla\u0308ndern der deutschen Entwicklungszusammenarbeit zu st\u00e4rken. Nicht zuletzt unterst\u00fctzt es die Verbreitung des in den Evaluierungen generierten Wissens. Dadurch sollen Lernprozesse gef\u00f6rdert und Entscheidungen in der Entwicklungszusammenarbeit erleichtert werden. Die Pr\u00e4sentation von J\u00f6rg Faust befindet sich <a href=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/2024-02-29DEval_Praesentation_Faust.pdf\" target=\"_blank\" rel=\"noopener\">hier<\/a>. Weitere Informationen zum DEval finden sich <a href=\"https:\/\/www.deval.org\/de\/\" target=\"_blank\" rel=\"noopener\">hier.<\/a><\/p>\n<h6><strong>M\u00f6glichkeiten und Grenzen der Wirkungsmessung in der IZA<\/strong> sieht J\u00f6rg Faust \u00fcber folgende 4 Hauptaspekte beeinflusst:<\/h6>\n<ol>\n<li>Auf der Angebotsseite bestehen grunds\u00e4tzlich sehr viele M\u00f6glichkeiten der Wirkungsmessung, zunehmend insbesondere durch anspruchsvolle Methoden bzw. deren Kombination und auch den Einsatz neuer Technologien (Big Data, KI, etc.). Entscheidend wird sein inwieweit Evaluierungseinheiten die Ressourcen (Zeit, Humankapital, Finanzen, Organisationskapital) hierf\u00fcr haben bzw. bekommen bzw. entwickeln k\u00f6nnen.<\/li>\n<li>Auf der Nutzungsseite h\u00e4ngt sehr viel von den institutionellen Rahmenbedingungen ab, welche die Nutzung unabh\u00e4ngiger und n\u00fctzlicher Evidenz beeinflussen (Evaluierungsstandards, Evaluierungsprozess, Einspeisung und Umsetzung von Empfehlungen).<\/li>\n<li>Sowohl auf der Angebots- wie auch auf der Nutzungsseite wird Evaluierung zunehmend einem Spagat zwischen st\u00e4rkeren Forderungen nach Partnerorientierung aber auch der Orientierung an den Interessen der Geberl\u00e4nder ausgesetzt sein.<\/li>\n<li>Zunehmende Konkurrenz: Die Evaluierung ist ein Anbieter auf dem hart umk\u00e4mpften Markt der Evidenz<\/li>\n<\/ol>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16411 size-full aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image2.jpg\" alt=\"\" width=\"346\" height=\"276\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image2.jpg 346w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image2-300x239.jpg 300w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><\/p>\n<p style=\"text-align: center;\">J\u00f6rg Faust (DEval)<\/p>\n<h5><strong>\u00a0<\/strong><strong>2. Evaluation der Wirksamkeitsmessung der Schweizer IZA<\/strong><\/h5>\n<p>Im Januar 2022 beauftragten die Gesch\u00e4ftspr\u00fcfungskommissionen der eidgen\u00f6ssischen R\u00e4te (GPK) die Parlamentarische Verwaltungskontrolle (PVK), die Wirksamkeitsmessung in der IZA zu evaluieren. Die PVK untersuchte die Wirksamkeit der IZA nicht selbst, sondern befasste sich vielmehr mit der Art und Weise, wie die drei f\u00fcr die IZA zust\u00e4ndigen Verwaltungseinheiten \u2013 die Direktion f\u00fcr Entwicklung und Zusammenarbeit (DEZA), das Staatssekretariat f\u00fcr Wirtschaft (SECO) und die Abteilung Frieden und Menschenrechte (AFM) \u2013 die Wirksamkeit ihrer Interventionen anhand von Evaluationen messen und dar\u00fcber Rechenschaft ablegen.<\/p>\n<p>Simone Ledermann hat zur <strong>Ausgangslage, der methodischen Herangehensweise und den Ergebnissen dieser PVK Evaluation<\/strong> berichtet:<\/p>\n<p>Die Evaluation hat auf 3 Aspekte fokussiert: 1) Qualit\u00e4t der Evaluationen und Hilfsmittel, 2) Nutzung der Evaluationen f\u00fcr Steuerung und Rechenschaftslegung, 3) Kosten der Evaluationen.<\/p>\n<ul>\n<li>Zu 1) Die St\u00e4rken der Qualit\u00e4t liegen auf den Pflichtenheften und den Zusammenfassungen und Schlussfolgerungen der Berichte, was n\u00fctzlich f\u00fcr die Steuerung ist. Schw\u00e4chen liegen bei der Darstellung der Methoden und Resultate der Berichte, was problematisch f\u00fcr die Rechenschaftslegung ist.<\/li>\n<li>Zu 2) Unabh\u00e4ngige Evaluationen zu \u00fcbergeordneten Themen werden f\u00fcr die strategische Steuerung genutzt, hier erfolgt eine systematische Nachverfolgung der Empfehlungen. Wogegen externe Evaluationen von Projekten zwar f\u00fcr die operative Steuerung der Aktivit\u00e4ten genutzt werden, aber ohne systematische Nachverfolgung der Empfehlungen. Aussagen, ob Ziele der IZA-Strategie erreicht werden, sind nicht m\u00f6glich, denn externe Evaluationen messen Zielerreichung nicht explizit und es gibt keine systematische Bilanz im Schlussbericht.<\/li>\n<li>Zu 3) Die Kosten der Evaluation werden insgesamt als transparent bewertet. Aber weniger als 2,5 % der Projektkosten werden durchschnittlich f\u00fcr eine externe Evaluation aufgewendet, was im internationalen Vergleich eher tief ist. Es gibt keinen Zusammenhang zwischen der Qualit\u00e4t externer Evaluationen und ihren Kosten.<\/li>\n<\/ul>\n<p>Die Pr\u00e4sentation von Simone Ledermann befindet sich <a href=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/2024-02-29PVK_Praesentation_Ledermann.pdf\" target=\"_blank\" rel=\"noopener\">hier<\/a> und der PVK-Bericht ist <a href=\"https:\/\/www.parlament.ch\/de\/organe\/kommissionen\/parlamentarische-verwaltungskontrolle-pvk\/publikationen-pvk\/evaluationsberichte-pvk\" target=\"_blank\" rel=\"noopener\">hier<\/a> ver\u00f6ffentlicht.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16412 size-full aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image3.jpg\" alt=\"\" width=\"367\" height=\"275\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image3.jpg 367w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image3-300x225.jpg 300w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/><\/p>\n<p style=\"text-align: center;\">Simone Ledermann (PVK)<\/p>\n<p>Silvana Hogg hat die<strong> Ansichten und Massnahmen der drei IZA-Einheiten <\/strong>(DEZA, SECO, AFM) zum PVK-Bericht zusammengefasst: Deren Evaluationsdienste haben selbst Qualit\u00e4tsl\u00fccken und Verbesserungsbedarf erkannt und erachten die Empfehlungen der PVK\/GPK-S als zielf\u00fchrend und umsetzbar. Um die Qualit\u00e4t der Evaluationen zu verbessern, sollen u.a. die Zusammenarbeit der Evaluationsdienste intensiviert, Evaluationshilfsmittel \u00fcberarbeitet (DEZA), Evaluationskapazit\u00e4ten der Programmverantwortlichen durch Ausbildungsmodule gest\u00e4rkt und die Nachverfolgung von Evaluationsempfehlungen zur Auflage gemacht werden. Eine Verbesserung der Rechenschaftslegung soll erreicht werden u.a. durch die \u00dcberpr\u00fcfung der Publikationspraxis und der Methodologie der Erfolgsquote, der Einf\u00fchrung einer gemeinsamen Quote f\u00fcr DEZA\/SECO, mehr ex-post Evaluationen und ein neues digitalisiertes System (DEZA), das repr\u00e4sentativere und nachvollziehbarere Aussagen zur Wirksamkeit der IZA systematisch erfasst.<\/p>\n<p>Die Pr\u00e4sentation von Silvana Hogg befindet sich <a href=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/2024-02-29PVK-Bericht-Ansichten-IZA_Hogg.pdf\" target=\"_blank\" rel=\"noopener\">hier<\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16413 size-full aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image4.jpg\" alt=\"\" width=\"365\" height=\"274\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image4.jpg 365w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image4-300x225.jpg 300w\" sizes=\"(max-width: 365px) 100vw, 365px\" \/><\/p>\n<p style=\"text-align: center;\">Silvana Hogg (DEZA)<\/p>\n<h5><strong>3. Paneldiskussion zur Wirkungsmessung der IZA<\/strong><\/h5>\n<p>In der abschliessenden Paneldiskussion moderiert von Kimon Schneider (NADEL ETHZ), tauschten sich J\u00f6rg Faust (DEval), Simone Ledermann (PVK), Reto Th\u00f6nen (DEZA) und Stefanie Krapp (IPDET) gemeinsam mit dem Publikum zu spezifischen Fragen hinsichtlich der Wirkung der IZA und Rolle der Evaluation aus, u.a. was sind die M\u00f6glichkeiten und Grenzen der Wirkungsmessung in der IZA, welche Kapazit\u00e4ten sind notwendig auf welchen Ebenen, wie kann das des Mikro-Makro-Paradoxon angesichts der Komplexit\u00e4t \u00fcberwunden werden, Aktualit\u00e4ten und Trends in der Evaluation von komplexen Themen (Klimafinanzierung, Digitalisierung, KI\/Big Data, erforderliche Kompetenzen, etc.).<\/p>\n<p>Kernelemente der Diskussion war der Hinweis, dass es f\u00fcr gute Wirkungsmessung methodisch eigentlich keine Grenzen gibt. Wichtig und Herausforderung zugleich sind das Vorhandensein eines \u00abevaluative thinking\u00bb besonders in der \u00f6ffentlichen Verwaltung und der erforderlichen neuen Kompetenzen, um mit BigData und KI Anwendungen umgehen zu k\u00f6nnen.<\/p>\n<p>Im Weiteren wurde die Organisation der Evaluationsfunktion in Entwicklungsagenturen diskutiert. Gem\u00e4ss DEval liegen klare Evidenzen vor, dass eine dezentral organisierte Evaluationsfunktion anf\u00e4lliger ist f\u00fcr Qualit\u00e4tsm\u00e4ngel als bei einer starken zentralen Evaluationsfunktion. Vereint waren die Panelisten in ihrem kritischen Blick auf die popul\u00e4re, aber realit\u00e4tsfremde politische Forderung, die Arbeit der staatlichen Entwicklungsagenturen anhand einer Erfolgsquote der durchgef\u00fchrten Projekte messen zu wollen.<\/p>\n<p><em> <img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16414 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image5-300x226.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image5-300x226.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image5-768x577.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image5.jpg 858w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/em><\/p>\n<p style=\"text-align: center;\">Die Panelisten von links nach rechts: J\u00f6rg Faust (DEval), Simone Ledermann (PVK), Reto Th\u00f6nen (DEZA),<br \/>\nStefanie Krapp (IPDET) und der Moderator Kimon Schneider (NADEL \/ ETHZ)<\/p>\n<p><em> <img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16415 size-full aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image6.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image6.jpg 369w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image6-300x225.jpg 300w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16416 size-full aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image7.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image7.jpg 369w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image7-300x225.jpg 300w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p>F\u00fcr die SEVAL AG Kompetenzen: Stefanie Krapp<\/p>\n<p>F\u00fcr die EFK: Mathias Rickli<\/p>\n<p>F\u00fcr die SEVAL AG IZA: Kimon Schneider<\/p>\n<hr \/>\n<h3 style=\"text-align: left;\"><strong>SEVAL Dialogreihe zwischen Evaluierenden und Auftraggebenden<\/strong><\/h3>\n<h4 style=\"text-align: left;\"><strong>2.<\/strong><strong style=\"font-size: 1.485rem;\">Dialogveranstaltung: \u201eVom Pflichtenheft zum Vertrag\u201c<\/strong><\/h4>\n<h6 style=\"text-align: left;\"><strong>23.05.2024, 17:00-19:00h, Zentrum f\u00fcr universit\u00e4re Weiterbildung\/Uni Bern<\/strong><\/h6>\n<h6 style=\"text-align: left;\"><strong>Veranstalter: SEVAL AGs Kompetenzen und Standards<\/strong><\/h6>\n<p>Eine von Beginn weg gute Zusammenarbeit zwischen Evaluierenden und Auftraggebenden ist ein wichtiger Erfolgsfaktor f\u00fcr eine gelingende und wirkungsvolle Evaluation. Im Rahmen der SEVAL-Veranstaltung \u201eAus- und Weiterbildung in der Evaluation \u2013 Quo Vadis?\u201c im April 2022 wurde insbesondere die Qualifizierung von Auftraggebenden als dringlichen Bedarf identifiziert, um dies zu gew\u00e4hrleisten. Die AG Kompetenzen der SEVAL organisiert daher eine vierteilige Dialog-Reihe zur F\u00f6rderung des Austauschs zwischen Auftraggebenden und Evaluierenden, zur Verbesserung ihrer Zusammenarbeit und zur Weiterentwicklung von Kompetenzen in verschiedenen Phasen einer Evaluation:<\/p>\n<ol>\n<li>Von der Evaluationsidee zum Pflichtenheft, 23.11.2023<\/li>\n<li><strong>Vom Pflichtenheft zum Vertrag, 23.05.2024<\/strong><\/li>\n<li>Vom Vertrag zum Evaluationsbericht, November 2024<\/li>\n<li>Vom Bericht zur Valorisierung, Fr\u00fchjahr 2025<\/li>\n<\/ol>\n<h6><strong>Teilnehmende und inhaltliche Foki<\/strong><\/h6>\n<p>An der zweiten Dialogveranstaltung haben sich 11 Evaluierende und 8 Auftraggebende zu zentralen Aspekten bei Ausschreibungen und Offerten ausgetauscht, u.a.: Wie finde und erkenne ich gute Evaluator:innen, Ausschreibungsarten und -verfahren, Kommunikation w\u00e4hrend der Offertenphase, Qualit\u00e4t und Umfang von Offerten, Bewertungskriterien, Vertragsverhandlungen, Auftragskl\u00e4rung.<\/p>\n<p>Nach einem R\u00fcckblick auf die letzte Dialogveranstaltung (siehe den Werkstattbericht in <a href=\"https:\/\/leges.weblaw.ch\/legesissues\/2024\/1\/die-schweizer-evalua_2f88878018.html\" target=\"_blank\" rel=\"noopener\">LeGes 35, 2024<\/a>, 1) haben die Evaluator:innen und Auftraggebenden von Evaluationen zun\u00e4chst in getrennten Gruppen Herausforderungen in dieser Phase aus je ihrer Perspektive gesammelt und anschliessend perspektiven\u00fcbergreifend diskutiert. Auf Basis der vielf\u00e4ltigen Herausforderungen wurden Spannungsfelder identifiziert und Handlungsans\u00e4tze entwickelt.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16417 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image8.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image8.jpg 653w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image8-300x226.jpg 300w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16418 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image9-300x225.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image9-300x225.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image9.jpg 654w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<h6><strong>Bezug zu den SEVAL Standards<\/strong><\/h6>\n<p>Einleitend zum Dialog hat Christian R\u00fcefli, Leiter der SEVAL Arbeitsgruppe Standards auf die SEVAL Standards mit besonderer Bedeutung in der Phase zwischen Pflichtenheft und Vertrag hingewiesen. \u00a0Bei Ausschreibung und Planung einer Evaluation werden Entscheidungen getroffen und Grundlagen gelegt, die f\u00fcr die Qualit\u00e4t einer Evaluation wichtig sind. Es geht dabei darum, die Inhalte, das Konzept, die Methodik, das Vorgehen und das Projektmanagement einer Evaluation so zu gestalten, dass diese ihren Zweck bestm\u00f6glich erf\u00fcllen und den Standards m\u00f6glichst gerecht werden k\u00f6nnen. Obwohl grunds\u00e4tzlich alle Kriterien in jeder Phase relevant sind, gilt es in der Phase zwischen Pflichtenheft und Vertrag insbesondere die folgenden Kriterien herauszustreichen:<\/p>\n<ul>\n<li>A1 Ergebnisoffenheit und Unvoreingenommenheit<\/li>\n<li>A4 Nutzungsorientierung<\/li>\n<li>A6 Sicherstellung der erforderlichen Kompetenzen<\/li>\n<li>B1 Kl\u00e4rung von Gegenstand, Zweck, Evaluationsfragestellungen und Nutzung<\/li>\n<li>B4 Evaluationsvereinbarung<\/li>\n<li>B5 Zweckm\u00e4ssiges Evaluationskonzept<\/li>\n<li>C5 Dokumentation der Evaluation<\/li>\n<\/ul>\n<p>Bei der Konzeption einer Evaluation k\u00f6nnen Auftraggebende und Evaluierende die Standards auf unterschiedliche Weise konkret nutzen: Auftraggebende bei der Ausschreibung, Evaluierende bei der Offerterstellung, beide Seiten beim Projektstart.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16419 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image10-300x225.jpg\" alt=\"\" width=\"369\" height=\"276\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image10-300x225.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image10.jpg 644w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16420 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image11-300x225.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image11-300x225.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image11.jpg 645w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<h6><strong>Herausforderungen in der Phase zwischen Pflichtenheft und Vertrag<\/strong><\/h6>\n<p><u>F\u00fcr Auftraggebende<\/u>:<\/p>\n<ul>\n<li>Eingrenzung des Evaluationsgegenstandes<\/li>\n<li>Formulierung \u00abguter\u00bb Evaluationsfragen, die mit dem vorhandenen Budget beantwortbar sind<\/li>\n<li>Umgang mit dem eigenen \u00abBauchgef\u00fchl\u00bb resp. mit der Intuition bei der Entscheidungsfindung<\/li>\n<li>Anbieter:innen ohne spezifische Evaluationskompetenz (Organisationsentwicklungsb\u00fcros, Beratungsinstitute oder Forschungseinrichtungen ohne entsprechende Spezialisierung)<\/li>\n<li>Evaluationsteams, die in der Offerte mit vielen kompetenten Mitarbeitenden vorgestellt werden, aber nicht alle in der Evaluation mitarbeiten<\/li>\n<\/ul>\n<p><u>F\u00fcr Evaluierende<\/u>:<\/p>\n<ul>\n<li>Erwartungen der Auftraggebenden sind oft zu hoch und die Evaluationsfragen zu umfassend im Verh\u00e4ltnis zum gegebenen Kostendach<\/li>\n<li>Schwieriger Umgang mit impliziten Erwartungen<\/li>\n<li>Oft schwer einsch\u00e4tzbare Konkurrenzsituation im Offertverfahren, aber der Aufwand f\u00fcr die Erarbeitung von Offerten ist recht hoch<\/li>\n<li>Fehlende Kompetenzen der Auftraggebenden kann implizieren, dass bei der Beurteilung der Angebote der Preis und nicht die Qualit\u00e4t im Vordergrund steht<\/li>\n<li>Zu kurze Fristen zur Einreichung von Offerten<\/li>\n<li>Keine M\u00f6glichkeit der R\u00fcckfragen im Offertenprozess<\/li>\n<li>Keine koh\u00e4rente Verwendung der Bewertungskriterien von Offerten<\/li>\n<li>Knappe oder inhaltlich nicht nachvollziehbare Absagen im Verh\u00e4ltnis zum Aufwand einer Offerterstellung<\/li>\n<li>Zur\u00fcckziehen von Ausschreibungen in der Offertenphase<\/li>\n<\/ul>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16421 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image12-300x226.jpg\" alt=\"\" width=\"369\" height=\"278\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image12-300x226.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image12-768x578.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image12.jpg 779w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<h6><strong>Spannungsfelder, die sich aus den Herausforderungen ergeben<\/strong><\/h6>\n<ul>\n<li><u>Vorgegebener Rahmen:<\/u> Die Evaluierenden begr\u00fcssen es, wenn die Vorgaben f\u00fcr eine Evaluation klar sind. W\u00e4hrend Auftraggebende mit zu geringen Evaluationskompetenzen eine Herausforderung f\u00fcr Evaluierende sein k\u00f6nnen, weil beispielsweise unrealistische Vorgaben gemacht werden, hat aber auch die zunehmende Professionalisierung von Auftraggebenden Schattenseiten: wenn Auftraggebende aufgrund ihrer eigenen Expertise die gew\u00fcnschte Evaluation allzu detailliert ausformulieren und beispielsweise die Datenquellen, die Erhebungsmethoden, die Stichprobengr\u00f6sse etc. bereits vorgegeben sind, bleibt wenig Gestaltungsspielraum. F\u00fcr Evaluierende ist es wichtig, ihre Expertise in die Diskussion einbringen und selbst ein angemessenes Evaluationsdesign entwickeln und vorschlagen zu k\u00f6nnen.<\/li>\n<li><u>Bewertung der Offerten<\/u>: F\u00fcr Auftraggebende wird eine vergleichende Bewertung potenziell schwieriger, je unterschiedlicher die eingereichten Offerten sind. Andererseits ist es f\u00fcr Auftraggebende interessant, wenn unterschiedliche methodische Zug\u00e4nge vorgeschlagen werden, aus denen ausgew\u00e4hlt werden kann.<\/li>\n<li><u>Flexibilit\u00e4t f\u00fcr Anpassungen:<\/u> Es ist herausfordernd, f\u00fcr eine mehrj\u00e4hrige Evaluation bereits in der Offertenphase den Umfang von Erhebungen \u00fcber die gesamte Dauer bestimmen und kalkulieren zu k\u00f6nnen, wenn noch nicht klar ist, wie sich der Evaluationsgegenstand \u00fcber die Jahre entwickeln wird und welche neuen Evaluationsfragen sich dadurch ergeben. Evaluierende w\u00fcnschen sich von Auftraggebenden klare Signale, dass adaptive Evaluationsans\u00e4tze willkommen sind, und Hinweise darauf, wie mit diesem Spannungsfeld zwischen verbindlicher Budgetierung und Adaptivit\u00e4t umgegangen werden soll.<\/li>\n<li><u>Vergabeverfahren:<\/u> Aus Sicht von Auftraggebenden kann es wertvoll sein, gezielt Institute einzuladen, mit denen es bereits bew\u00e4hrte Zusammenarbeiten gibt. F\u00fcr diese Institute ist ein solches Vorgehen angenehm. Allerdings beschr\u00e4nkt es den Wettbewerb und erschwert es neuen Evaluator:innen, im Feld Fuss fassen zu k\u00f6nnen. Wenn breiter ausgeschrieben wird, steigt potenziell zwar der Aufwand f\u00fcr die Beurteilung der Offerten, aber neue Evaluator:innen bereichern den Wettbewerb und erhalten so eine Chance, sich zeigen und bew\u00e4hren zu k\u00f6nnen.<\/li>\n<\/ul>\n<h6><strong>Handlungsans\u00e4tze<\/strong><\/h6>\n<p>In der K\u00fcrze der Zeit wurden folgende Ans\u00e4tze thematisiert, welche eine gute Zusammenarbeit zwischen Auftraggebenden und Evaluierenden f\u00f6rdern:<\/p>\n<ul>\n<li>Klare und transparente Erwartungen in Ausschreibungen, aber Gestaltungsspielraum lassen, damit Evaluator:innen ihre methodische Expertise angemessen einbringen k\u00f6nnen.<\/li>\n<li>R\u00fcckfragen erm\u00f6glichen und die Kl\u00e4rungen gut dokumentieren und allen Interessierten zug\u00e4nglich machen.<\/li>\n<li>Neuen Evaluationsinstituten die Gelegenheit geben, sich zu pr\u00e4sentieren, sei dies im Rahmen von \u00f6ffentlichen Ausschreibungen, spezifischen Anl\u00e4ssen f\u00fcr Evaluationsinstitute oder bilateralen Pr\u00e4sentationsgespr\u00e4chen, und\/oder Konsortien f\u00f6rdern.<\/li>\n<li>Mehrstufige, selektive Verfahren durchf\u00fchren, um Evaluationsinstituten gleiche Chancen zu geben und den Aufwand trotzdem in Grenzen zu halten.<\/li>\n<li>Bei der Beurteilung von Offerten Bewertungsgremien einsetzen.<\/li>\n<li>Evaluationskompetenzen bei der Beurteilung von Offerten explizit hoch gewichten.<\/li>\n<li>Erm\u00f6glichung von adaptiven Designs, damit die Evaluation den Entwicklungen des Untersuchungsgegenstandes angepasst werden kann.<\/li>\n<li>Absagen ausf\u00fchrlich und mit Bezug zu den Vorgaben und Bewertungskriterien nachvollziehbar begr\u00fcnden.<\/li>\n<li>Explizite Angabe der Rollen der beteiligten Evaluator:innen in den Offerten.<\/li>\n<\/ul>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16422 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image13-300x225.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image13-300x225.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image13-768x577.jpg 768w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image13.jpg 865w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<h6><strong>Fazit <\/strong><\/h6>\n<p>Auch in dieser zweiten Veranstaltung hat sich gezeigt, wie wichtig ein Dialog zwischen Auftraggebenden und Evaluierenden ist, jenseits von konkreten Auftragsverh\u00e4ltnissen. Der Dialog gibt \u2018neuen\u2019 Evaluierenden im Feld die M\u00f6glichkeit, sich zu zeigen. Auftraggebende und Evaluierende k\u00f6nnen sich unbeschwert kennenlernen und offen diskutieren. Ein konstruktiver Dialog zu den Erfahrungen und Herausforderungen in der Phase der Ausschreibung einer Evaluation bis zum Vertrag aus der jeweils anderen Perspektive hat stattgefunden und n\u00fctzliche Handlungsans\u00e4tze wurden gemeinsam erarbeitet.<\/p>\n<p>Der n\u00e4chste Dialog \u201cVom Vertrag zum Evaluationsbericht\u201c folgt im November 2024.<\/p>\n<p>Veranstaltungsort: Zentrum f\u00fcr universit\u00e4re Weiterbildung, Universit\u00e4t Bern, Geb\u00e4ude UniS, Schanzeneckstr. 1.<\/p>\n<p>Es sind alle Teilnehmenden der beiden ersten Veranstaltung, aber auch neue Auftraggebende und Evaluierende herzlich eingeladen!<\/p>\n<p>Anmeldung an: <a href=\"&#109;&#x61;i&#x6c;&#x74;&#111;&#x3a;e&#x76;&#x61;&#108;&#x75;a&#x74;&#x69;&#111;&#x6e;&#46;&#x7a;&#x75;&#119;&#x40;u&#x6e;&#x69;&#98;&#x65;&#46;&#x63;&#x68;\">&#101;&#118;&#x61;l&#117;&#x61;&#x74;i&#111;&#x6e;&#x2e;z&#117;&#x77;&#64;&#117;&#x6e;&#x69;b&#101;&#x2e;&#x63;h<\/a><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16423 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image14-300x225.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image14-300x225.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image14.jpg 670w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-16424 aligncenter\" src=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image15-300x226.jpg\" alt=\"\" width=\"369\" height=\"277\" srcset=\"https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image15-300x226.jpg 300w, https:\/\/www.seval.ch\/app\/uploads\/2024\/07\/Image15.jpg 673w\" sizes=\"(max-width: 369px) 100vw, 369px\" \/><\/p>\n<p>G\u00fcnter Ackermann &amp; Stefanie Krapp (SEVAL AG Kompetenzen)<\/p>\n<p>Christian R\u00fcefli (SEVAL AG Standards)<\/p>\n<hr \/>\n<h4><strong>AG Kompetenzen<\/strong><\/h4>\n<ul>\n<li><strong>Netzwerktreffen 2024 des DACH-Netzwerks f\u00fcr Gesundheitsf\u00f6rderung<\/strong>:<br \/>\nAm 20.\/21. September 2024 findet an der ZHAW in Winterthur ein Netzwerktreffen des DACH-Netzwerks f\u00fcr Gesundheitsf\u00f6rderung statt. Es handelt sich um ein offenes Netzwerk, an dem man sich frei beteiligen kann. Einer der drei Schwerpunktthemen des diesj\u00e4hrigen Treffens ist \u00abEvaluation in der Gesundheitsf\u00f6rderung und Pr\u00e4vention.\u00bb Es geht um eine Standortbestimmung (in den L\u00e4ndern der DACH-Region \u2013 Deutschland, \u00d6sterreich und die Schweiz) und um das Bestimmen von Synergien und Entwicklungslinien. Evaluationsfachleute, die an diesem \u00dcberblick und Austausch zu \u00abEvaluation und Wirkungsforschung in Gesundheitsf\u00f6rderung und Pr\u00e4vention\u00bb interessiert sind, k\u00f6nnen sich \u00fcber die <a href=\"https:\/\/www.zhaw.ch\/de\/gesundheit\/ueber-uns\/veranstaltungen\/veranstaltungsdetails\/event-news\/dach-netzwerk-fuer-gesundheitsfoerderung-netzwerktreffen-2024\/\" target=\"_blank\" rel=\"noopener\">Veranstaltungswebseite<\/a> informieren und anmelden.<\/li>\n<li><strong>Eval-training.org:<\/strong> Die Plattform f\u00fcr Aus- und Weiterbildung in Evaluation wurde neu programmiert und ist nun wieder voll funktionsf\u00e4hig: <a href=\"http:\/\/www.eval-training.org\" target=\"_blank\" rel=\"noopener\">eval-training.org<\/a>. Bitte anstehende Aus- und Weiterbildungsangebote laufend erfassen! Die Nutzerdaten und die laufenden Angebote wurden \u00fcbernommen, bereits abgeschlossene Angebote nicht.<\/li>\n<\/ul>\n<hr \/>\n<h4><strong>Buchprojekt \u00abSEVAL-Evaluationsstandards in der Praxis\u00bb &#8211; Aufruf f\u00fcr Beitr\u00e4ge<\/strong><\/h4>\n<p>Die SEVAL-Arbeitsgruppen Forschung \u00fcber Evaluation und Evaluationsstandards planen ein Buch zur Praxis der Anwendung der SEVAL-Standards. Das Buch soll Praxisbeispiele, Diskussionsbeitr\u00e4ge sowie wissenschaftliche Artikel aus Sicht verschiedener Stakeholder enthalten. Das Herausgeberteam (Andreas Balthasar, Lars Balzer, Nicolas Grosjean, C\u00e9line Mavrot, Christian R\u00fcefli und Reinhard Zweidler) l\u00e4dt alle Interessierten ein, Vorschl\u00e4ge f\u00fcr Buchbeitr\u00e4ge einzureichen. Ein ausf\u00fchrlicher Call for Papers findet sich <a href=\"https:\/\/www.seval.ch\/2024\/07\/01\/buchprojekt-seval-evaluationsstandards-in-der-praxis-aufruf-fuer-beitraege\/\" target=\"_blank\" rel=\"noopener\">hier<\/a>. Absichtserkl\u00e4rungen f\u00fcr Beitr\u00e4ge k\u00f6nnen bis am 1. Oktober 2024 eingereicht werden.<\/p>\n<p>&nbsp;<\/p>\n<h3><a id=\"absatz_6\"><\/a>Agenda<\/h3>\n<hr \/>\n<p>News und Veranstaltungen finden Sie fortlaufend <a href=\"https:\/\/www.seval.ch\/news-veranstaltungen\/\" target=\"_blank\" rel=\"noopener noreferrer\">hier<\/a><\/p>\n<p><strong>Zur Erinnerung:<\/strong> wenn Sie als Mitglied der SEVAL an einer Veranstaltung teilnehmen m\u00f6chten und anschliessend einen kurzen Beitrag dazu ver\u00f6ffentlichen, welche Erkenntnisse Sie aus dieser Veranstaltung gewonnen haben, k\u00f6nnen Sie f\u00fcr Ihre Transportkosten, Unterkunft und Registrierung eine Entsch\u00e4digung von max. CHF 1\u2019000.- beantragen. Ihren schriftlichen Beitrag ver\u00f6ffentlichen wir im Newsletter. Bitte kontaktieren Sie in der Phase der Vorbereitung Ihrer Reise das SEVAL-Sekretariat <a href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;&#58;&#x73;e&#x63;r&#x65;t&#x61;r&#105;&#x61;&#116;&#x40;&#115;&#x65;&#118;&#x61;&#108;&#x2e;c&#x68;\">s&#101;&#x63;&#x72;e&#116;&#x61;&#x72;i&#97;&#116;&#x40;&#x73;e&#118;&#x61;&#x6c;&#46;&#99;&#x68;<\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><a id=\"absatz_6\"><\/a>Publikationen<\/h3>\n<hr \/>\n<p>Die Rubrik <strong>Publikationen<\/strong> bietet eine Plattform, um auf Neuerscheinungen zum Thema Evaluation oder auf Publikationen von Seval-Mitgliedern (Evaluationsberichte, B\u00fccher, Artikel in B\u00fcchern oder Fachzeitschriften etc.) aufmerksam zu machen. Entsprechende Hinweise nimmt die Redaktion jederzeit gerne entgegen: <a href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;:&#x73;e&#x63;r&#101;&#x74;&#97;&#x72;&#105;&#x61;&#116;&#x40;s&#x65;v&#x61;l&#46;&#x63;&#104;\">&#115;&#x65;c&#114;&#x65;t&#97;&#x72;i&#97;&#x74;&#64;&#115;&#x65;v&#97;&#x6c;&#46;&#99;&#x68;<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"template":"","mailing-list":[43],"acf":[],"_links":{"self":[{"href":"https:\/\/www.seval.ch\/it\/wp-json\/wp\/v2\/newsletter\/16397"}],"collection":[{"href":"https:\/\/www.seval.ch\/it\/wp-json\/wp\/v2\/newsletter"}],"about":[{"href":"https:\/\/www.seval.ch\/it\/wp-json\/wp\/v2\/types\/newsletter"}],"version-history":[{"count":28,"href":"https:\/\/www.seval.ch\/it\/wp-json\/wp\/v2\/newsletter\/16397\/revisions"}],"predecessor-version":[{"id":16473,"href":"https:\/\/www.seval.ch\/it\/wp-json\/wp\/v2\/newsletter\/16397\/revisions\/16473"}],"wp:attachment":[{"href":"https:\/\/www.seval.ch\/it\/wp-json\/wp\/v2\/media?parent=16397"}],"wp:term":[{"taxonomy":"mailing-list","embeddable":true,"href":"https:\/\/www.seval.ch\/it\/wp-json\/wp\/v2\/mailing-list?post=16397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}