{"id":16055,"date":"2024-05-15T16:04:35","date_gmt":"2024-05-15T14:04:35","guid":{"rendered":"https:\/\/www.seval.ch\/2024\/05\/15\/webinaire-sur-evaluation-des-odd-au-niveau-decentralise-loutil-barometre\/"},"modified":"2024-05-21T16:27:52","modified_gmt":"2024-05-21T14:27:52","slug":"webinaire-sur-evaluation-des-odd-au-niveau-decentralise-loutil-barometre","status":"publish","type":"post","link":"https:\/\/www.seval.ch\/fr\/2024\/05\/15\/webinaire-sur-evaluation-des-odd-au-niveau-decentralise-loutil-barometre\/","title":{"rendered":"Webinaire sur &#8220;\u00c9valuation des ODD au niveau d\u00e9centralis\u00e9 : l\u2019outil Barom\u00e8tre&#8221;"},"content":{"rendered":"<div>Le RFE organise un webinaire sur &#8220;\u00c9valuation des ODD au niveau d\u00e9centralis\u00e9 : l\u2019outil Barom\u00e8tre&#8221;, le 23 mai 2024, de 13h00 \u00e0 14h00 GMT.<\/div>\n<div><\/div>\n<div>Cet \u00e9v\u00e9nement s&#8217;inscrit dans le cadre d&#8217;une s\u00e9rie de webinaire que nous allons proposer tout le long de l&#8217;ann\u00e9e 2024.<\/div>\n<div><\/div>\n<div>Les personnes int\u00e9ress\u00e9es sont invit\u00e9es \u00e0 s&#8217;inscrire, au plus tard pour le mercredi 22 mai 2024, \u00e0 12h00 GMT.<\/div>\n<div><\/div>\n<div>Vous trouvez de plus amples informations <a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeF6EcVJF7rgMOCAwqo3Nc2Ahl7yY0FWaIsFowZs13at_dnfg\/viewform\" target=\"_blank\" rel=\"noopener\">ici<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le RFE organise un webinaire sur &#8220;\u00c9valuation des ODD au niveau d\u00e9centralis\u00e9 : l\u2019outil Barom\u00e8tre&#8221;, le 23 mai 2024, de 13h00 \u00e0 14h00 GMT. Cet \u00e9v\u00e9nement s&#8217;inscrit dans le cadre d&#8217;une s\u00e9rie de webinaire que nous allons proposer tout le long de l&#8217;ann\u00e9e 2024. Les personnes int\u00e9ress\u00e9es sont invit\u00e9es \u00e0 s&#8217;inscrire, au plus tard pour &hellip;<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_searchwp_excluded":""},"categories":[98],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/posts\/16055"}],"collection":[{"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/comments?post=16055"}],"version-history":[{"count":2,"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/posts\/16055\/revisions"}],"predecessor-version":[{"id":16070,"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/posts\/16055\/revisions\/16070"}],"wp:attachment":[{"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/media?parent=16055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/categories?post=16055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seval.ch\/fr\/wp-json\/wp\/v2\/tags?post=16055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}