{"id":16658,"date":"2024-11-18T12:37:26","date_gmt":"2024-11-18T11:37:26","guid":{"rendered":"https:\/\/www.seval.ch\/2024\/09\/10\/improvisationstheater-zur-durchfuehrungsphase-einer-evaluation\/"},"modified":"2024-11-18T14:14:38","modified_gmt":"2024-11-18T13:14:38","slug":"improvisationstheater-zur-durchfuehrungsphase-einer-evaluation","status":"publish","type":"post","link":"https:\/\/www.seval.ch\/en\/2024\/11\/18\/improvisationstheater-zur-durchfuehrungsphase-einer-evaluation\/","title":{"rendered":"Improvisationstheater zur Durchf\u00fchrungsphase einer Evaluation"},"content":{"rendered":"<p>Die AG Kompetenzen der SEVAL organisiert eine vierteilige Dialog-Reihe zur F\u00f6rderung des Austauschs zwischen Auftraggebenden und Evaluierenden, zur Verbesserung ihrer Zusammenarbeit und zur Weiterentwicklung von Kompetenzen in verschiedenen Phasen einer Evaluation. Gerne laden wir Sie zum n\u00e4chsten Austausch ein:<\/p>\n<h4>SEVAL Dialog mal ganz anders! Teil 3 \u201cVom Vertrag zum Evaluationsbericht\u201c im\u00a0 Forumtheaterformat<\/h4>\n<p>In Zusammenarbeit mit dem Improtheater <a href=\"https:\/\/pfirsi.ch\/\" target=\"_blank\" rel=\"noopener\">Anundpfirsich<\/a><\/p>\n<p><strong>Donnerstag 28.11.2024<\/strong><\/p>\n<p><strong>17.00-19.00 Uhr, mit anschliessendem Apero<\/strong><\/p>\n<p>Veranstaltungsort: Zentrum f\u00fcr universit\u00e4re Weiterbildung, Universit\u00e4t Bern, Geb\u00e4ude UniS, Schanzeneckstr. 1, Raum S003 (H\u00f6rsaal im EG).<\/p>\n<p>Anmeldung bitte bis 21.11.2024 an: <a href=\"&#x6d;&#97;i&#x6c;&#116;o&#x3a;&#101;v&#x61;&#108;u&#x61;&#116;i&#x6f;&#110;&#46;&#x7a;&#117;w&#x40;&#117;n&#x69;&#98;e&#x2e;&#99;h\">&#x65;&#118;&#97;l&#x75;&#x61;&#116;i&#x6f;&#x6e;&#46;z&#x75;&#x77;&#64;u&#x6e;&#x69;&#98;e&#x2e;&#x63;&#104;<\/a><\/p>\n<p>Wie k\u00f6nnen m\u00f6gliche Konflikte zwischen Auftraggebenden und Evaluierenden w\u00e4hrend der Umsetzung einer Evaluation besser dargestellt werden als in einem Theater? Freuen Sie sich auf einen lebhaften und interaktiven Abend zur Erarbeitung von L\u00f6sungen!<\/p>\n<p>Erkenntnisse aus den beiden ersten Dialogen (Teil 1 &#8220;Von der Evaluationsidee zum Pflichtenheft&#8221;, Teil 2 &#8220;Vom Pflichtenheft zum Vertrag&#8221;):<\/p>\n<p>In LeGes ist ein <a href=\"https:\/\/leges.weblaw.ch\/legesissues\/2024\/1\/die-schweizer-evalua_2f88878018.html\" target=\"_blank\" rel=\"noopener\">Werkstattbericht<\/a> \u00fcber die erste und ein <a href=\"https:\/\/leges.weblaw.ch\/legesissues\/2024\/2\/seval-dialogreihe-zw_ed92b51b46.html\" target=\"_blank\" rel=\"noopener\">Werkstattbericht<\/a> \u00fcber die zweite Dialogveranstaltung erschienen.<\/p>\n<p>Das Video mit Teilnehmendenstimmen zum ersten Dialog kann <a href=\"https:\/\/www.youtube.com\/watch?v=NnKdcQavCxc\" target=\"_blank\" rel=\"noopener\">HIER<\/a> angeschaut werden!<\/p>\n<p>G\u00fcnter Ackermann, Qualit\u00e4t und Evaluation, Leitung AG Kompetenzen der SEVAL<\/p>\n<p>Stefanie Krapp, Bereich Evaluation ZUW\/Uni Bern, Mitglied der AG Kompetenzen<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die AG Kompetenzen der SEVAL organisiert eine vierteilige Dialog-Reihe zur F\u00f6rderung des Austauschs zwischen Auftraggebenden und Evaluierenden, zur Verbesserung ihrer Zusammenarbeit und zur Weiterentwicklung von Kompetenzen in verschiedenen Phasen einer Evaluation. Gerne laden wir Sie zum n\u00e4chsten Austausch ein: SEVAL Dialog mal ganz anders! Teil 3 \u201cVom Vertrag zum Evaluationsbericht\u201c im\u00a0 Forumtheaterformat In Zusammenarbeit mit &hellip;<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_searchwp_excluded":""},"categories":[136,132],"tags":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/posts\/16658"}],"collection":[{"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/comments?post=16658"}],"version-history":[{"count":5,"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/posts\/16658\/revisions"}],"predecessor-version":[{"id":17087,"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/posts\/16658\/revisions\/17087"}],"wp:attachment":[{"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/media?parent=16658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/categories?post=16658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seval.ch\/en\/wp-json\/wp\/v2\/tags?post=16658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}